{"id":994,"count":1,"description":"","link":"https:\/\/kernmedia.ch\/index.php\/tag\/venezianische-partei-england-whig-junto\/","name":"Venezianische Partei England Whig Junto","slug":"venezianische-partei-england-whig-junto","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/tags\/994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/posts?tags=994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}