{"id":1013,"count":1,"description":"","link":"https:\/\/kernmedia.ch\/index.php\/tag\/elitebildung-ostkuestenoligarchie-roosevelts\/","name":"Elitebildung Ostkuestenoligarchie Roosevelts","slug":"elitebildung-ostkuestenoligarchie-roosevelts","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/tags\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kernmedia.ch\/index.php\/wp-json\/wp\/v2\/posts?tags=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}